{"id":110094,"date":"2026-07-15T08:58:47","date_gmt":"2026-07-15T06:58:47","guid":{"rendered":"https:\/\/dze-csv.it\/?p=110094"},"modified":"2026-07-15T09:50:54","modified_gmt":"2026-07-15T07:50:54","slug":"nuovo-sportello-di-consulenza-per-le-persone-con-disabilita","status":"publish","type":"post","link":"https:\/\/dze-csv.it\/it\/nuovo-sportello-di-consulenza-per-le-persone-con-disabilita\/","title":{"rendered":"Nuovo Sportello di Consulenza per le Persone con Disabilit\u00e0"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row row_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_visibility=&#8221;yes&#8221; mobile_visibility=&#8221;yes&#8221; inverted_device_order=&#8221;yes&#8221;][vc_column width=&#8221;1\/1&#8243;][uncode_slider slider_interval=&#8221;5000&#8243; slider_navspeed=&#8221;400&#8243; slider_loop=&#8221;yes&#8221; slider_hide_arrows=&#8221;yes&#8221; slider_dot_position=&#8221;left&#8221; slider_dot_width=&#8221;limit&#8221; slider_width_percent=&#8221;100&#8243; h_padding=&#8221;2&#8243; slider_dot_align=&#8221;left&#8221;][vc_row_inner row_inner_height_percent=&#8221;100&#8243; back_color=&#8221;color-134241&#8243; overlay_alpha=&#8221;20&#8243; gutter_size=&#8221;4&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; el_class=&#8221;versicherungsschutz&#8221; row_height_pixel=&#8221;400px&#8221;][vc_column_inner column_width_percent=&#8221;100&#8243; position_horizontal=&#8221;left&#8221; position_vertical=&#8221;bottom&#8221; gutter_size=&#8221;2&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; css_animation=&#8221;right-t-left&#8221; zoom_width=&#8221;0&#8243; zoom_height=&#8221;0&#8243; width=&#8221;1\/1&#8243; css=&#8221;.vc_custom_1594366474544{padding-left: 36px !important;}&#8221;][vc_custom_heading heading_semantic=&#8221;h1&#8243; text_font=&#8221;font-255343&#8243; text_size=&#8221;fontsize-155944&#8243; text_weight=&#8221;200&#8243; text_space=&#8221;fontspace-781688&#8243; uncode_shortcode_id=&#8221;643099&#8243;]Nuovo Sportello di Consulenza per le Persone con Disabilit\u00e0[\/vc_custom_heading][vc_empty_space empty_h=&#8221;1&#8243;][vc_separator sep_color=&#8221;,Default&#8221;][\/vc_column_inner][\/vc_row_inner][\/uncode_slider][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; desktop_visibility=&#8221;yes&#8221;][vc_column width=&#8221;1\/1&#8243;][uncode_slider slider_interval=&#8221;5000&#8243; slider_navspeed=&#8221;400&#8243; slider_loop=&#8221;yes&#8221; slider_hide_arrows=&#8221;yes&#8221; slider_dot_position=&#8221;left&#8221; slider_dot_width=&#8221;limit&#8221; slider_width_percent=&#8221;100&#8243; h_padding=&#8221;2&#8243; slider_dot_align=&#8221;left&#8221;][vc_row_inner row_inner_height_percent=&#8221;100&#8243; back_color=&#8221;color-134241&#8243; overlay_alpha=&#8221;20&#8243; gutter_size=&#8221;4&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column_inner column_width_percent=&#8221;100&#8243; position_horizontal=&#8221;left&#8221; position_vertical=&#8221;bottom&#8221; gutter_size=&#8221;2&#8243; style=&#8221;dark&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; css_animation=&#8221;right-t-left&#8221; animation_delay=&#8221;600&#8243; zoom_width=&#8221;0&#8243; zoom_height=&#8221;0&#8243; width=&#8221;1\/1&#8243; css=&#8221;.vc_custom_1594366464284{padding-left: 2rem !important;}&#8221;][vc_separator sep_color=&#8221;,Default&#8221;][vc_custom_heading text_font=&#8221;font-255343&#8243; text_size=&#8221;fontsize-338686&#8243; text_weight=&#8221;200&#8243; text_space=&#8221;fontspace-781688&#8243; uncode_shortcode_id=&#8221;197011&#8243;]Nuovo Sportello di Consulenza per le Persone con Disabilit\u00e0[\/vc_custom_heading][vc_empty_space empty_h=&#8221;1&#8243;][vc_separator sep_color=&#8221;,Default&#8221;][\/vc_column_inner][\/vc_row_inner][\/uncode_slider][\/vc_column][\/vc_row][vc_row][vc_column column_width_percent=&#8221;80&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; css_animation=&#8221;left-t-right&#8221; width=&#8221;1\/3&#8243;][vc_empty_space empty_h=&#8221;2&#8243;][vc_separator sep_color=&#8221;color-134241&#8243;][vc_button button_color=&#8221;color-134241&#8243; wide=&#8221;yes&#8221; custom_typo=&#8221;yes&#8221; font_family=&#8221;font-255343&#8243; font_weight=&#8221;500&#8243; italic=&#8221;yes&#8221; border_width=&#8221;0&#8243; css_animation=&#8221;bottom-t-top&#8221; link=&#8221;url:https%3A%2F%2Fdze-csv.it%2Fwp-content%2Fuploads%2F2026%2F07%2FFlyer-bilingue.pdf|target:_blank&#8221; button_color_type=&#8221;uncode-palette&#8221; uncode_shortcode_id=&#8221;193991&#8243;]Flyer[\/vc_button][vc_button button_color=&#8221;color-134241&#8243; wide=&#8221;yes&#8221; custom_typo=&#8221;yes&#8221; font_family=&#8221;font-255343&#8243; font_weight=&#8221;500&#8243; italic=&#8221;yes&#8221; border_width=&#8221;0&#8243; css_animation=&#8221;bottom-t-top&#8221; link=&#8221;url:https%3A%2F%2Fdze-csv.it%2Fwp-content%2Fuploads%2F2026%2F07%2Flettera-Sportello-per-le-persone-con-disabilita-signed.pdf|target:_blank&#8221; button_color_type=&#8221;uncode-palette&#8221; uncode_shortcode_id=&#8221;242075&#8243;]Tutte le informazioni[\/vc_button][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; css_animation=&#8221;right-t-left&#8221; width=&#8221;2\/3&#8243;][vc_empty_space empty_h=&#8221;2&#8243;][vc_separator sep_color=&#8221;color-wvjs&#8221;][vc_column_text uncode_shortcode_id=&#8221;143466&#8243;]<\/p>\n<p class=\"isSelectedEnd\">Il Comune di Bolzano ha attivato un nuovo <strong>Sportello di Consulenza per le Persone con Disabilit\u00e0<\/strong>. Il servizio \u00e8 rivolto alle persone con disabilit\u00e0, ai loro familiari e a tutte le cittadine e i cittadini che necessitano di informazioni, orientamento o supporto sui temi legati alla disabilit\u00e0.<\/p>\n<p class=\"isSelectedEnd\">Lo sportello intende rafforzare il dialogo diretto tra la popolazione e l\u2019amministrazione comunale e offrire un punto di riferimento facilmente accessibile per diverse esigenze.<\/p>\n<h2>Consulenza, orientamento e supporto<\/h2>\n<p class=\"isSelectedEnd\">Tra i principali compiti del nuovo sportello rientrano:<\/p>\n<ul data-spread=\"false\">\n<li>la consulenza e l\u2019informazione sui servizi, sulle opportunit\u00e0 e sulle forme di supporto disponibili sul territorio comunale;<\/li>\n<li>la creazione di un canale di comunicazione diretto tra cittadine e cittadini e l\u2019amministrazione comunale;<\/li>\n<li>la raccolta di bisogni, richieste, segnalazioni e osservazioni;<\/li>\n<li>la promozione dell\u2019inclusione e della partecipazione attiva delle persone con disabilit\u00e0.<\/li>\n<\/ul>\n<h2>Sede e orari di apertura<\/h2>\n<p class=\"isSelectedEnd\">Lo sportello si trova presso:<\/p>\n<p class=\"isSelectedEnd\"><strong>Centro Civico<\/strong><br \/>\nVicolo Gumer 7, Bolzano<br \/>\nPiano terra<\/p>\n<p class=\"isSelectedEnd\">Le consulenze si svolgono <strong>ogni gioved\u00ec dalle ore 15.00 alle ore 17.00<\/strong>.<\/p>\n<p class=\"isSelectedEnd\">L\u2019accesso \u00e8 possibile esclusivamente previo appuntamento.<\/p>\n<h2>Referenti<\/h2>\n<p class=\"isSelectedEnd\">Sono a disposizione come referenti:<\/p>\n<p class=\"isSelectedEnd\"><strong>Claudio Palmulli<\/strong><br \/>\nPresidente della Consulta comunale per le persone con disabilit\u00e0 e referente del Consiglio comunale<\/p>\n<p class=\"isSelectedEnd\"><strong>Ulrich Seitz<\/strong><br \/>\nReferente fiduciario del Sindaco per le persone con disabilit\u00e0<\/p>\n<h2>Prenotazione degli appuntamenti<\/h2>\n<p class=\"isSelectedEnd\">\u00c8 possibile fissare un appuntamento tramite e-mail:<\/p>\n<ul data-spread=\"false\">\n<li><a href=\"mailto:claudio.palmulli@comune.bolzano.it\">claudio.palmulli@comune.bolzano.it<\/a><\/li>\n<li><a href=\"mailto:ulrich.seitz@comune.bolzano.it\">ulrich.seitz@comune.bolzano.it<\/a><\/li>\n<\/ul>\n<p>Ulteriori informazioni sul servizio sono disponibili sul sito del Comune di Bolzano, alla pagina <strong>\u00abSportello di consulenza per le persone con disabilit\u00e0\u00bb:<\/strong><\/p>\n<p>https:\/\/www.comune.bolzano.bz.it\/Vivere-il-Comune\/Luoghi\/Sportello-di-consulenza-per-le-persone-con-disabilita[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/1&#8243;][vc_empty_space empty_h=&#8221;3&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row row_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_visibility=&#8221;yes&#8221; mobile_visibility=&#8221;yes&#8221; inverted_device_order=&#8221;yes&#8221;][vc_column width=&#8221;1\/1&#8243;][uncode_slider slider_interval=&#8221;5000&#8243; slider_navspeed=&#8221;400&#8243; slider_loop=&#8221;yes&#8221; slider_hide_arrows=&#8221;yes&#8221; slider_dot_position=&#8221;left&#8221; slider_dot_width=&#8221;limit&#8221; slider_width_percent=&#8221;100&#8243; h_padding=&#8221;2&#8243; slider_dot_align=&#8221;left&#8221;][vc_row_inner [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":110103,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[94],"tags":[],"class_list":["post-110094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-volontariato"],"acf":[],"_links":{"self":[{"href":"https:\/\/dze-csv.it\/it\/wp-json\/wp\/v2\/posts\/110094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dze-csv.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dze-csv.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dze-csv.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dze-csv.it\/it\/wp-json\/wp\/v2\/comments?post=110094"}],"version-history":[{"count":3,"href":"https:\/\/dze-csv.it\/it\/wp-json\/wp\/v2\/posts\/110094\/revisions"}],"predecessor-version":[{"id":110107,"href":"https:\/\/dze-csv.it\/it\/wp-json\/wp\/v2\/posts\/110094\/revisions\/110107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dze-csv.it\/it\/wp-json\/wp\/v2\/media\/110103"}],"wp:attachment":[{"href":"https:\/\/dze-csv.it\/it\/wp-json\/wp\/v2\/media?parent=110094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dze-csv.it\/it\/wp-json\/wp\/v2\/categories?post=110094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dze-csv.it\/it\/wp-json\/wp\/v2\/tags?post=110094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}